{"id":1044,"date":"2017-12-21T11:12:07","date_gmt":"2017-12-21T16:12:07","guid":{"rendered":"https:\/\/ecarrieres.com\/?p=1044"},"modified":"2018-05-16T15:13:35","modified_gmt":"2018-05-16T19:13:35","slug":"universite-teluq","status":"publish","type":"post","link":"https:\/\/ecarrieres.com\/fr\/universite-teluq\/","title":{"rendered":"Exposant \u00e0 la Une : UNIVERSIT\u00c9 T\u00c9LUQ"},"content":{"rendered":"<p>[et_pb_section bb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb3.0.101&Prime; background_color_gradient_direction=\u00a0\u00bb128deg\u00a0\u00bb border_color_all=\u00a0\u00bb#ffffff\u00a0\u00bb border_width_right=\u00a0\u00bb15px\u00a0\u00bb border_width_left=\u00a0\u00bb15px\u00a0\u00bb module_alignment=\u00a0\u00bbright\u00a0\u00bb custom_margin=\u00a0\u00bb|||\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px|\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/ecarrieres.com\/wp-content\/uploads\/2018\/02\/exposant_une_bandeau.jpg\u00a0\u00bb next_background_color=\u00a0\u00bb#000000&Prime;][et_pb_row make_fullwidth=\u00a0\u00bbon\u00a0\u00bb use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb1&Prime; custom_padding=\u00a0\u00bb0px|0px|41px|0px\u00a0\u00bb custom_margin=\u00a0\u00bb0px|0px|0px|0px\u00a0\u00bb padding_top_1=\u00a0\u00bb4vw\u00a0\u00bb padding_right_1=\u00a0\u00bb4vw\u00a0\u00bb padding_bottom_1=\u00a0\u00bb4vw\u00a0\u00bb padding_left_1=\u00a0\u00bb4vw\u00a0\u00bb padding_top_2=\u00a0\u00bb4vw\u00a0\u00bb padding_right_2=\u00a0\u00bb4vw\u00a0\u00bb padding_bottom_2=\u00a0\u00bb4vw\u00a0\u00bb padding_left_2=\u00a0\u00bb4vw\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.89&Prime; module_alignment=\u00a0\u00bbcenter\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime;][et_pb_text admin_label=\u00a0\u00bb\u00c9v\u00e9nement carri\u00e8res\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.91&Prime; header_font_size=\u00a0\u00bb32px\u00a0\u00bb header_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb header_2_font=\u00a0\u00bbSource Sans Pro||on||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb29px\u00a0\u00bb header_2_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb header_2_letter_spacing=\u00a0\u00bb3px\u00a0\u00bb custom_margin=\u00a0\u00bb|||\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb0px|||\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb custom_padding=\u00a0\u00bb||0.5vw|\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb header_3_font_size=\u00a0\u00bb24px\u00a0\u00bb header_3_text_align=\u00a0\u00bbcenter\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\">L&rsquo;\u00c9v\u00e9nement Carri\u00e8res<\/h3>\n<p>[\/et_pb_text][et_pb_divider show_divider=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.91&Prime; height=\u00a0\u00bb28px\u00a0\u00bb divider_style=\u00a0\u00bbdotted\u00a0\u00bb divider_weight=\u00a0\u00bb4px\u00a0\u00bb max_width=\u00a0\u00bb12%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb \/][et_pb_text admin_label=\u00a0\u00bbTitre de l&rsquo;article\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.98&Prime; header_font_size=\u00a0\u00bb42px\u00a0\u00bb header_text_color=\u00a0\u00bb#4ecdc4&Prime; header_2_font=\u00a0\u00bbSource Sans Pro||on||||||\u00a0\u00bb header_2_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_2_font_size=\u00a0\u00bb42px\u00a0\u00bb header_2_text_color=\u00a0\u00bb#4ecdc4&Prime; header_2_letter_spacing=\u00a0\u00bb3px\u00a0\u00bb custom_margin=\u00a0\u00bb0px|||\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb custom_padding=\u00a0\u00bb2vw|||\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.1em\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb header_font=\u00a0\u00bbSource Sans Pro||on||||||\u00a0\u00bb]<\/p>\n<h1 style=\"text-align: center;\">Universit\u00e9 T\u00c9LUQ<\/h1>\n<p>[\/et_pb_text][et_pb_post_title _builder_version=\u00a0\u00bb3.0.101&Prime; title=\u00a0\u00bboff\u00a0\u00bb meta=\u00a0\u00bbon\u00a0\u00bb author=\u00a0\u00bboff\u00a0\u00bb date=\u00a0\u00bbon\u00a0\u00bb categories=\u00a0\u00bbon\u00a0\u00bb comments=\u00a0\u00bboff\u00a0\u00bb featured_image=\u00a0\u00bboff\u00a0\u00bb featured_placement=\u00a0\u00bbbelow\u00a0\u00bb text_color=\u00a0\u00bblight\u00a0\u00bb text_background=\u00a0\u00bboff\u00a0\u00bb disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb disabled=\u00a0\u00bboff\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb saved_tabs=\u00a0\u00bball\u00a0\u00bb date_format=\u00a0\u00bbj M Y\u00a0\u00bb \/][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section bb_built=\u00a0\u00bb1&Prime; background_color=\u00a0\u00bb#ffffff\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.89&Prime; background_color_gradient_direction=\u00a0\u00bb153deg\u00a0\u00bb border_width_right=\u00a0\u00bb15px\u00a0\u00bb border_color_right=\u00a0\u00bb#ffffff\u00a0\u00bb border_width_left=\u00a0\u00bb15px\u00a0\u00bb border_color_left=\u00a0\u00bb#ffffff\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb custom_padding=\u00a0\u00bb24px|0px|17px|0px\u00a0\u00bb disabled=\u00a0\u00bboff\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb prev_background_color=\u00a0\u00bb#000000&Prime; next_background_color=\u00a0\u00bb#4ecdc4&Prime;][et_pb_row custom_padding=\u00a0\u00bb2vw|4vw|2vw|4vw\u00a0\u00bb custom_margin=\u00a0\u00bb|||\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.91&Prime; make_fullwidth=\u00a0\u00bbon\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime;][et_pb_image _builder_version=\u00a0\u00bb3.0.91&Prime; src=\u00a0\u00bbhttps:\/\/ecarrieres.com\/wp-content\/uploads\/2017\/12\/guylaine_handfiel-3.jpg\u00a0\u00bb show_in_lightbox=\u00a0\u00bboff\u00a0\u00bb url_new_window=\u00a0\u00bboff\u00a0\u00bb use_overlay=\u00a0\u00bboff\u00a0\u00bb always_center_on_mobile=\u00a0\u00bbon\u00a0\u00bb force_fullwidth=\u00a0\u00bboff\u00a0\u00bb show_bottom_space=\u00a0\u00bbon\u00a0\u00bb \/][\/et_pb_column][et_pb_column type=\u00a0\u00bb2_3&Prime;][et_pb_text admin_label=\u00a0\u00bbintro\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.98&Prime; text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_text_color=\u00a0\u00bb#191b31&Prime; custom_margin=\u00a0\u00bb|||\u00a0\u00bb custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb0px|||\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size=\u00a0\u00bb28px\u00a0\u00bb header_2_text_align=\u00a0\u00bbleft\u00a0\u00bb header_2_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb]<\/p>\n<h3>Entrevue avec Guylaine Handfield<\/h3>\n<p>Conseill\u00e8re d&rsquo;orientation \u00e0 l&rsquo;Universit\u00e9 T\u00c9LUQ<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb3.0.91&Prime; make_fullwidth=\u00a0\u00bbon\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime;][et_pb_text admin_label=\u00a0\u00bbCorps du texte\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.98&Prime; text_font_size=\u00a0\u00bb15px\u00a0\u00bb text_text_color=\u00a0\u00bb#191b31&Prime; custom_margin=\u00a0\u00bb|||\u00a0\u00bb custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding_phone=\u00a0\u00bb0px|||\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb]<\/p>\n<h3>Pouvez-vous nous pr\u00e9senter votre universit\u00e9 et votre fonction en quelques mots? Qu\u2019est ce qui fait de vous une \u00e9cole de choix?<\/h3>\n<p><strong>Guylaine Handfield :<\/strong> L\u2019Universit\u00e9 T\u00c9LUQ est la seule universit\u00e9 francophone enti\u00e8rement \u00e0 distance en Am\u00e9rique du Nord. Elle fait partie du grand r\u00e9seau des Universit\u00e9s du Qu\u00e9bec et elle f\u00eate ses 45 ans cette ann\u00e9e. \u00c0 ce jour, nous recevons 20 000 \u00e9tudiants chaque ann\u00e9e, dans 4 d\u00e9partements qui proposent 80 programmes et 400 cours aux 3 cycles d\u2019\u00e9tudes.<\/p>\n<p>Ici, pas de salle de classe ni de rendez-vous devant l\u2019\u00e9cran. On \u00e9tudie o\u00f9 et quand on le souhaite. Souplesse et flexibilit\u00e9 dans le cheminement sont donc notre distinction et un facilitant \u00e9vident pour favoriser la r\u00e9ussite.<\/p>\n<p>\u00c0 titre de conseill\u00e8re d\u2019orientation et responsable du service d\u2019aide en orientation de l\u2019Universit\u00e9, je fournis de l\u2019information scolaire et professionnelle, je recueille et analyse les besoins, je conseille les \u00e9tudiants face \u00e0 leur choix de carri\u00e8re, j\u2019aide les \u00e9tudiants dans l\u2019identification de leurs habilet\u00e9s et int\u00e9r\u00eats pour les orienter dans leur choix de programme, etc.<\/p>\n<p>[\/et_pb_text][et_pb_video _builder_version=\u00a0\u00bb3.0.98&Prime; src=\u00a0\u00bbhttps:\/\/www.youtube.com\/watch?v=vp69NvhqXAs\u00a0\u00bb \/][et_pb_text admin_label=\u00a0\u00bbCorps du texte\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.98&Prime; text_font_size=\u00a0\u00bb15px\u00a0\u00bb text_text_color=\u00a0\u00bb#191b31&Prime; custom_margin=\u00a0\u00bb|||\u00a0\u00bb custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding_phone=\u00a0\u00bb0px|||\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb]<\/p>\n<h3>Quels sont les avantages de l\u2019enseignement \u00e0 distance et sur quels points faut-il \u00eatre vigilant en tant qu\u2019\u00e9tudiant?<\/h3>\n<p><strong>Guylaine Handfield :<\/strong> Ne pas devoir se d\u00e9placer sur un campus selon un horaire pr\u00e9cis est certainement un grand avantage. Il est alors possible d\u2019\u00e9tudier tout en travaillant. Pour celles et ceux qui ont une famille \u00e0 charge, il s\u2019agit l\u00e0 d\u2019une opportunit\u00e9 exceptionnelle pour pouvoir concilier les diverses responsabilit\u00e9s.<\/p>\n<p>Il faut toutefois \u00eatre conscient que les \u00e9tudes \u00e0 distance demandent une autonomie de la part de l\u2019\u00e9tudiant. Il doit faire preuve de constance et de rigueur. Il doit utiliser les personnes-ressources et les services qui lui sont offerts pour maximiser ses \u00e9tudes et favoriser sa r\u00e9ussite.<\/p>\n<p>De plus, il est n\u00e9cessaire de faire une bonne \u00e9valuation de temps r\u00e9el que l\u2019on a \u00e0 investir dans ses \u00e9tudes. Les cours ne doivent pas devenir une pression suppl\u00e9mentaire sur les \u00e9paules.<\/p>\n<p>&nbsp;<\/p>\n<h3>Quel(s) conseil(s) donneriez-vous aux \u00e9tudiants pour choisir la bonne formation?<\/h3>\n<p><strong>Guylaine Handfield :<\/strong> Dans un premier temps, d\u00e9finissez vos besoins. R\u00e9fl\u00e9chissez \u00e0 ce que vous souhaitez en entreprenant des \u00e9tudes : obtenir un dipl\u00f4me universitaire ou compl\u00e9ter votre formation initiale ; am\u00e9liorer vos conditions de travail, vous perfectionner, r\u00e9orienter votre carri\u00e8re ; obtenir plus de responsabilit\u00e9s au travail ; faire reconna\u00eetre vos comp\u00e9tences ; rester actif intellectuellement ou satisfaire vos aspirations personnelles, etc.<\/p>\n<p>Dans un deuxi\u00e8me temps, pr\u00e9cisez la dur\u00e9e de votre projet d\u2019\u00e9tudes en fonction de vos objectifs. Combien de temps pouvez-vous investir dans vos \u00e9tudes? Quel programme convient \u00e0 vos besoins?<\/p>\n<p>Prenez le temps de r\u00e9fl\u00e9chir : Comment les \u00e9tudes que vous d\u00e9sirez entreprendre vous seront utiles? Comment pourrez-vous passer \u00e0 l&rsquo;action? Finalement, d\u00e9terminez un plan d\u2019action qui guidera vos choix pour la suite. Attention, aucun choix n\u2019est immuable et laissez-vous le droit \u00e0 l\u2019erreur. Mieux vaut arr\u00eater un projet qui ne fait plus sens pour vous que de poursuivre dans une voie sans issue!<\/p>\n<p>&nbsp;<\/p>\n<h3>Quels dipl\u00f4mes selon vous sont les plus recherch\u00e9s par les recruteurs?<\/h3>\n<p><strong>Guylaine Handfield :<\/strong> Pour les postes de niveau professionnel ou cadre, un grade de 1er cycle universitaire est fr\u00e9quemment exig\u00e9. Un baccalaur\u00e9at, voire une ma\u00eetrise, sont impos\u00e9s pour bon nombre d\u2019ordres, d\u2019instituts et d\u2019associations professionnelles. Les dipl\u00f4mes de 1er cycle universitaires (entre autres les certificats, majeures et mineures) peuvent se cumuler pour finalement obtenir un grade de 1er cycle. En plus d\u2019atteindre le niveau d\u2019\u00e9tudes souvent requis, les \u00e9tudiants peuvent ainsi faire des choix plus personnalis\u00e9s qui correspondent r\u00e9ellement \u00e0 leurs int\u00e9r\u00eats.<\/p>\n<p>Pour celles et ceux qui ont d\u00e9j\u00e0 en poche un dipl\u00f4me d\u2019\u00e9tudes universitaires de 1er cycle, les baccalaur\u00e9ats par composantes peuvent repr\u00e9senter une excellente alternative pour utiliser les cr\u00e9dits d\u00e9j\u00e0 acquis et compl\u00e9ter leur formation initiale.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_image _builder_version=\u00a0\u00bb3.0.98&Prime; src=\u00a0\u00bbhttps:\/\/ecarrieres.com\/wp-content\/uploads\/2017\/12\/logo_teluq_rvb_1952x1041.svg\u00a0\u00bb show_in_lightbox=\u00a0\u00bboff\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb use_overlay=\u00a0\u00bboff\u00a0\u00bb always_center_on_mobile=\u00a0\u00bbon\u00a0\u00bb force_fullwidth=\u00a0\u00bboff\u00a0\u00bb show_bottom_space=\u00a0\u00bbon\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb max_width=\u00a0\u00bb50%\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.teluq.ca\/\u00a0\u00bb \/][\/et_pb_column][\/et_pb_row][et_pb_row][et_pb_column type=\u00a0\u00bb4_4&Prime;][et_pb_text admin_label=\u00a0\u00bbCorps du texte\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.98&Prime; text_font_size=\u00a0\u00bb15px\u00a0\u00bb text_text_color=\u00a0\u00bb#191b31&Prime; custom_margin=\u00a0\u00bb|||\u00a0\u00bb custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding_phone=\u00a0\u00bb0px|||\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb]<\/p>\n<h3>Quel(s) conseil(s) donneriez-vous aux \u00e9tudiants pour r\u00e9ussir leurs \u00e9tudes \u00e0 distance?<\/h3>\n<p><strong>Guylaine Handfield :<\/strong> Aimez ce que vous \u00e9tudiez! La motivation n\u2019en sera que plus soutenue et elle vous aidera \u00e0 traverser les p\u00e9riodes plus difficiles. Utilisez les ressources d\u2019encadrement : professeurs, charg\u00e9s d\u2019encadrement, tuteurs, votre \u00e9quipe programme. Puisque vous n\u2019aurez pas de professeurs pour vous r\u00e9sumer la mati\u00e8re en 3 heures de cours, vous aurez assur\u00e9ment des questions et des doutes, et c\u2019est normal! Ces ressources sont l\u00e0 pour vous aider \u00e0 y voir clair et vous amener \u00e0 bien comprendre la th\u00e9orie. Plusieurs professionnels, techniciens et commis sont \u00e9galement pr\u00e9sents pour vous soutenir. Que ce soit pour vous soutenir dans votre r\u00e9ussite, vous donner de l\u2019information g\u00e9n\u00e9rale ou des pr\u00e9cisions sur votre dossier et votre cheminement, toute une \u00e9quipe est pr\u00e9sente pour vous.<\/p>\n<p>Demeurez r\u00e9aliste dans la gestion de vos r\u00f4les et \u00e9vitez les objectifs irr\u00e9alistes. Vaut mieux avancer \u00e0 petits pas que d\u2019en prendre trop \u00e0 la fois.<\/p>\n<p>&nbsp;<\/p>\n<h3>Un dernier mot pour les visiteurs cherchant une formation?<\/h3>\n<p><strong>Guylaine Handfield :<\/strong> La formation \u00e0 distance est en plein essor et vous verrez bon nombre de nouveaux programmes faire leur entr\u00e9e dans divers \u00e9tablissements de la province. Riche de 45 ans d\u2019exp\u00e9rience, l\u2019Universit\u00e9 T\u00c9LUQ est la seule universit\u00e9 qui se concentre uniquement sur la formule d\u2019\u00e9tudes \u00e0 distance, et ce, depuis sa cr\u00e9ation. En collaboration avec les professeurs, les sp\u00e9cialistes en sciences de l\u2019\u00e9ducation et en technologies \u00e9ducatives travaillent avec acharnement pour cr\u00e9er des cours adapt\u00e9s, dynamiques et surtout, int\u00e9ressants pour \u00eatre suivis \u00e0 distance. Avec ses outils technop\u00e9dagogiques, l\u2019Universit\u00e9 T\u00c9LUQ a cr\u00e9\u00e9 divers environnements d\u2019apprentissage novateurs qui facilitent l\u2019\u00e9tude et le travail. Pas besoin d\u2019\u00eatre un pro de la techno pour \u00e9tudier chez nous! Une connaissance de base d\u2019Internet et des logiciels de r\u00e9daction suffisent.<\/p>\n<p>Mon conseil ultime : osez vous informer!<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section bb_built=\u00a0\u00bb1&Prime; background_color=\u00a0\u00bb#4ecdc4&Prime; _builder_version=\u00a0\u00bb3.0.98&Prime; background_color_gradient_direction=\u00a0\u00bb128deg\u00a0\u00bb border_color_all=\u00a0\u00bb#ffffff\u00a0\u00bb border_width_top=\u00a0\u00bb15px\u00a0\u00bb border_width_right=\u00a0\u00bb15px\u00a0\u00bb border_width_left=\u00a0\u00bb15px\u00a0\u00bb module_alignment=\u00a0\u00bbright\u00a0\u00bb custom_margin=\u00a0\u00bb|||\u00a0\u00bb custom_padding=\u00a0\u00bb0px|0px|0px|0px\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb prev_background_color=\u00a0\u00bb#ffffff\u00a0\u00bb next_background_color=\u00a0\u00bb#ffffff\u00a0\u00bb][et_pb_row make_fullwidth=\u00a0\u00bbon\u00a0\u00bb use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb1&Prime; custom_padding=\u00a0\u00bb0px||0px|\u00a0\u00bb custom_margin=\u00a0\u00bb0px|0px|0px|0px\u00a0\u00bb bg_img_3=\u00a0\u00bbhttps:\/\/ecarrieres.com\/wp-content\/uploads\/2017\/12\/event500x500-2.jpg\u00a0\u00bb padding_top_1=\u00a0\u00bb0px\u00a0\u00bb padding_bottom_1=\u00a0\u00bb0px\u00a0\u00bb padding_top_2=\u00a0\u00bb0px\u00a0\u00bb padding_bottom_2=\u00a0\u00bb0px\u00a0\u00bb padding_top_3=\u00a0\u00bb0px\u00a0\u00bb padding_bottom_3=\u00a0\u00bb0px\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.91&Prime; module_alignment=\u00a0\u00bbcenter\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime;][et_pb_text admin_label=\u00a0\u00bbVenez rencontrer\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.98&Prime; text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_text_color=\u00a0\u00bb#191b31&Prime; custom_margin=\u00a0\u00bb|||\u00a0\u00bb custom_padding=\u00a0\u00bb2vw|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb0px|||\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb header_2_font_size=\u00a0\u00bb35px\u00a0\u00bb header_2_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_2_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb]<\/p>\n<h2>Venez rencontrer T\u00c9LUQ<\/h2>\n<p>[\/et_pb_text][et_pb_button admin_label=\u00a0\u00bbVoir la fiche d&rsquo;exposant\u00a0\u00bb button_url=\u00a0\u00bb#\u00a0\u00bb button_text=\u00a0\u00bbVoir la fiche d&rsquo;exposant\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.98&Prime; custom_margin=\u00a0\u00bb1vw||2vw|\u00a0\u00bb custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb20px\u00a0\u00bb button_text_color=\u00a0\u00bb#191b31&Prime; button_border_color=\u00a0\u00bb#191b31&Prime; button_icon=\u00a0\u00bb%%43%%\u00a0\u00bb button_text_color_hover=\u00a0\u00bb#4ecdc4&Prime; button_bg_color_hover=\u00a0\u00bb#191b31&Prime; button_border_color_hover=\u00a0\u00bb#191b31&Prime; animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_speed_curve=\u00a0\u00bbease-in\u00a0\u00bb url_new_window=\u00a0\u00bboff\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb button_icon_placement=\u00a0\u00bbright\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb \/][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section bb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb3.0.91&Prime; background_image=\u00a0\u00bbhttps:\/\/ecarrieres.com\/wp-content\/uploads\/2017\/12\/fond-evenement.jpg\u00a0\u00bb border_width_right=\u00a0\u00bb15px\u00a0\u00bb border_color_right=\u00a0\u00bb#ffffff\u00a0\u00bb border_color_left=\u00a0\u00bb#ffffff\u00a0\u00bb border_width_left=\u00a0\u00bb15px\u00a0\u00bb custom_padding=\u00a0\u00bb54px|0px|104px|0px\u00a0\u00bb disabled=\u00a0\u00bboff\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb prev_background_color=\u00a0\u00bb#4ecdc4&Prime;][et_pb_row][et_pb_column type=\u00a0\u00bb4_4&Prime;][et_pb_text admin_label=\u00a0\u00bbrestez en contact\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.91&Prime; text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_text_color=\u00a0\u00bb#191b31&Prime; custom_margin=\u00a0\u00bb|||\u00a0\u00bb custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb0px|||\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size=\u00a0\u00bb35px\u00a0\u00bb header_2_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_2_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb header_2_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb]<\/p>\n<h2>Restez en contact avec T\u00c9LUQ<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb3.0.89&Prime;][et_pb_column type=\u00a0\u00bb1_2&Prime;][et_pb_text _builder_version=\u00a0\u00bb3.0.98&Prime; background_layout=\u00a0\u00bbdark\u00a0\u00bb]<\/p>\n<h4>Coordonn\u00e9es<\/h4>\n<p><strong>T\u00e9l\u00e9phone : <a href=\"tel:1 888 843-4333\">1 888 843-4333<\/a><\/strong><br \/>\n<strong> Courriel : <a href=\"mailto:info@teluq.ca\">info@teluq.ca<\/a><\/strong><br \/>\n<strong> Site web : <a href=\"https:\/\/www.teluq.ca\/\" target=\"_blank\" rel=\"noopener\">teluq.ca<\/a><\/strong><\/p>\n<p><strong>Toutes les infos <a href=\"https:\/\/www.teluq.ca\/site\/infos\/joindre.php\" target=\"_blank\" rel=\"noopener\">pour nous joindre<\/a><\/strong><\/p>\n<p><strong>Infos pour les <a href=\"https:\/\/www.teluq.ca\/site\/etudes\/futurs_etudiants.php\" target=\"_blank\" rel=\"noopener\">futurs \u00e9tudiants<\/a><\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime;][et_pb_blurb admin_label=\u00a0\u00bbfacebook\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.91&Prime; url=\u00a0\u00bbhttps:\/\/www.facebook.com\/universiteteluq\/\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb%%291%%\u00a0\u00bb use_circle=\u00a0\u00bboff\u00a0\u00bb use_circle_border=\u00a0\u00bbon\u00a0\u00bb icon_placement=\u00a0\u00bbleft\u00a0\u00bb use_icon_font_size=\u00a0\u00bbon\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb icon_font_size=\u00a0\u00bb25px\u00a0\u00bb animation_style=\u00a0\u00bbbounce\u00a0\u00bb \/][et_pb_blurb admin_label=\u00a0\u00bbtwitter\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.91&Prime; url=\u00a0\u00bbhttps:\/\/twitter.com\/teluq\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb%%292%%\u00a0\u00bb use_circle=\u00a0\u00bboff\u00a0\u00bb use_circle_border=\u00a0\u00bbon\u00a0\u00bb icon_placement=\u00a0\u00bbleft\u00a0\u00bb use_icon_font_size=\u00a0\u00bbon\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb icon_font_size=\u00a0\u00bb25px\u00a0\u00bb animation_style=\u00a0\u00bbbounce\u00a0\u00bb \/][et_pb_blurb admin_label=\u00a0\u00bblinkedin\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.91&Prime; url=\u00a0\u00bbhttps:\/\/www.linkedin.com\/groups\/2261708\/profile\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb%%301%%\u00a0\u00bb use_circle=\u00a0\u00bboff\u00a0\u00bb use_circle_border=\u00a0\u00bbon\u00a0\u00bb icon_placement=\u00a0\u00bbleft\u00a0\u00bb use_icon_font_size=\u00a0\u00bbon\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb icon_font_size=\u00a0\u00bb25px\u00a0\u00bb animation_style=\u00a0\u00bbbounce\u00a0\u00bb \/][et_pb_blurb admin_label=\u00a0\u00bbgoogle +\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.91&Prime; url=\u00a0\u00bbhttps:\/\/plus.google.com\/u\/0\/117030030450914816714&Prime; url_new_window=\u00a0\u00bbon\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb%%294%%\u00a0\u00bb use_circle=\u00a0\u00bboff\u00a0\u00bb use_circle_border=\u00a0\u00bbon\u00a0\u00bb icon_placement=\u00a0\u00bbleft\u00a0\u00bb use_icon_font_size=\u00a0\u00bbon\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb icon_font_size=\u00a0\u00bb25px\u00a0\u00bb animation_style=\u00a0\u00bbbounce\u00a0\u00bb \/][et_pb_blurb admin_label=\u00a0\u00bbyoutube\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.91&Prime; url=\u00a0\u00bbhttps:\/\/www.youtube.com\/channel\/UCXA_KH9CeTMcioNX5nirn_A\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb%%307%%\u00a0\u00bb use_circle=\u00a0\u00bboff\u00a0\u00bb use_circle_border=\u00a0\u00bbon\u00a0\u00bb icon_placement=\u00a0\u00bbleft\u00a0\u00bb use_icon_font_size=\u00a0\u00bbon\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb icon_font_size=\u00a0\u00bb25px\u00a0\u00bb animation_style=\u00a0\u00bbbounce\u00a0\u00bb \/][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime;][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrevue avec Guylaine Handfield, Conseill\u00e8re d&rsquo;orientation \u00e0 l&rsquo;Universit\u00e9 T\u00c9LUQ<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","wds_primary_category":0,"footnotes":""},"categories":[46],"tags":[],"class_list":["post-1044","post","type-post","status-publish","format-standard","hentry","category-exposant-a-la-une"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:57:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ecarrieres.com\/fr\/wp-json\/wp\/v2\/posts\/1044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecarrieres.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecarrieres.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecarrieres.com\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/ecarrieres.com\/fr\/wp-json\/wp\/v2\/comments?post=1044"}],"version-history":[{"count":60,"href":"https:\/\/ecarrieres.com\/fr\/wp-json\/wp\/v2\/posts\/1044\/revisions"}],"predecessor-version":[{"id":1710,"href":"https:\/\/ecarrieres.com\/fr\/wp-json\/wp\/v2\/posts\/1044\/revisions\/1710"}],"wp:attachment":[{"href":"https:\/\/ecarrieres.com\/fr\/wp-json\/wp\/v2\/media?parent=1044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecarrieres.com\/fr\/wp-json\/wp\/v2\/categories?post=1044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecarrieres.com\/fr\/wp-json\/wp\/v2\/tags?post=1044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}